{"id":862,"count":47,"description":"","link":"https:\/\/dev.starandstampstore.com\/en\/product-category\/afrika-2\/madagascar-afrika-2\/","name":"Madagascar","slug":"madagascar-afrika-2","taxonomy":"product_cat","parent":320,"meta":[],"_links":{"self":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat\/862"}],"collection":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat\/320"}],"wp:post_type":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product?product_cat=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}