{"id":456,"count":12,"description":"","link":"https:\/\/dev.starandstampstore.com\/en\/product-category\/europa\/bosnien-och-hercegovina\/","name":"Bosnien och Hercegovina","slug":"bosnien-och-hercegovina","taxonomy":"product_cat","parent":54,"meta":[],"_links":{"self":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat\/456"}],"collection":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat\/54"}],"wp:post_type":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product?product_cat=456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}