{"id":1195,"count":2,"description":"","link":"https:\/\/dev.starandstampstore.com\/en\/product-category\/engelska-samvaldet\/indien\/indiska-stater\/travancore-cochin-indiska-stater\/","name":"Travancore-Cochin","slug":"travancore-cochin-indiska-stater","taxonomy":"product_cat","parent":688,"meta":[],"_links":{"self":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat\/1195"}],"collection":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product_cat\/688"}],"wp:post_type":[{"href":"https:\/\/dev.starandstampstore.com\/en\/wp-json\/wp\/v2\/product?product_cat=1195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}